{"id":16598,"date":"2026-05-07T08:50:45","date_gmt":"2026-05-07T11:50:45","guid":{"rendered":"https:\/\/www.tvuai.com.br\/portal\/?p=16598"},"modified":"2026-05-07T18:49:30","modified_gmt":"2026-05-07T21:49:30","slug":"vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre","status":"publish","type":"post","link":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/","title":{"rendered":"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre"},"content":{"rendered":"<div class=\"5a1038e0903b96d426fcfcc338703013\" data-index=\"1\" style=\"float: right; margin:10px 0 10px 10px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-9945944833605257\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-9945944833605257\"\r\n     data-ad-slot=\"2343923581\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<h5 style=\"text-align: center;\" data-start=\"91\" data-end=\"240\"><em><strong>Campanha mobiliza escolas da regi\u00e3o de Pouso Alegre para ampliar cobertura vacinal de estudantes e profissionais da educa\u00e7\u00e3o<\/strong><\/em><\/h5>\n<p data-start=\"322\" data-end=\"670\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"16600\" data-permalink=\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/vacina\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina.jpg?fit=800%2C450&amp;ssl=1\" data-orig-size=\"800,450\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778105641&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"vacina\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina.jpg?fit=300%2C169&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina.jpg?fit=640%2C360&amp;ssl=1\" tabindex=\"0\" role=\"button\" class=\"aligncenter size-full wp-image-16600\" src=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina.jpg?resize=640%2C360&#038;ssl=1\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>A campanha de vacina\u00e7\u00e3o nas escolas mobilizou 365 unidades de ensino em 45 munic\u00edpios da \u00e1rea atendida pela Superintend\u00eancia Regional de Sa\u00fade de <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Pouso Alegre<\/span><\/span>. A a\u00e7\u00e3o, realizada entre os dias 4 a 8 de maio, busca ampliar a cobertura vacinal entre crian\u00e7as, adolescentes, jovens e profissionais da educa\u00e7\u00e3o em todo o estado.<\/p>\n<p data-start=\"672\" data-end=\"807\">A iniciativa \u00e9 promovida pelas secretarias de Estado de Sa\u00fade e de Educa\u00e7\u00e3o de Minas Gerais, em parceria com as secretarias municipais.<\/p>\n<p data-start=\"809\" data-end=\"1096\">A abertura regional da mobiliza\u00e7\u00e3o ocorreu em <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Pouso Alegre<\/span><\/span>\u00a0com um Dia D de vacina\u00e7\u00e3o realizado na Escola Municipal Caic S\u00e3o Jo\u00e3o. O foco da campanha \u00e9 atualizar os cart\u00f5es de vacina\u00e7\u00e3o e facilitar o acesso \u00e0s doses previstas no Calend\u00e1rio Nacional de Vacina\u00e7\u00e3o.<\/p>\n<p data-start=\"1098\" data-end=\"1278\">Segundo a superintendente regional de Sa\u00fade, Adriana Ferreira, levar a vacina\u00e7\u00e3o para dentro das escolas ajuda a ampliar a prote\u00e7\u00e3o coletiva e reduzir o risco de doen\u00e7as evit\u00e1veis.<\/p>\n<p data-start=\"1280\" data-end=\"1418\">\u201cAs vacinas s\u00e3o seguras, eficazes e salvam vidas. Manter a caderneta atualizada \u00e9 um ato de responsabilidade e cuidado coletivo\u201d, afirmou.<\/p>\n<p data-start=\"1420\" data-end=\"1595\">A superintendente destacou ainda que a mobiliza\u00e7\u00e3o depende da integra\u00e7\u00e3o entre sa\u00fade e educa\u00e7\u00e3o para alcan\u00e7ar a meta de 90% de cobertura vacinal entre crian\u00e7as e adolescentes.<\/p>\n<p data-start=\"1597\" data-end=\"1829\">Durante a campanha, est\u00e3o sendo disponibilizadas todas as vacinas previstas no calend\u00e1rio nacional, conforme a faixa et\u00e1ria e a situa\u00e7\u00e3o vacinal de cada estudante, al\u00e9m das doses de campanhas em andamento, como influenza e covid-19.<\/p>\n<p data-start=\"1831\" data-end=\"1933\">O p\u00fablico-alvo inclui estudantes que estejam com vacinas em atraso, al\u00e9m de profissionais da educa\u00e7\u00e3o.<\/p>\n<p data-start=\"1935\" data-end=\"2101\">Para a diretora educacional da Superintend\u00eancia Regional de Ensino de Pouso Alegre, Rafaelly Gomes, a vacina\u00e7\u00e3o tamb\u00e9m contribui para um ambiente escolar mais seguro.<\/p>\n<p data-start=\"2103\" data-end=\"2279\">\u201cA Secretaria de Estado de Educa\u00e7\u00e3o aderiu \u00e0 campanha com a mobiliza\u00e7\u00e3o de todas as unidades escolares. Estamos incentivando a participa\u00e7\u00e3o de estudantes e fam\u00edlias\u201d, declarou.<\/p>\n<h6 style=\"text-align: right;\" data-start=\"2103\" data-end=\"2279\"><em><strong>Com informa\u00e7\u00f5es e foto de Ot\u00e1vio Coutinho<\/strong><\/em><\/h6>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre' data-link='https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Campanha mobiliza escolas da regi\u00e3o de Pouso Alegre para ampliar cobertura vacinal de estudantes e profissionais da educa\u00e7\u00e3o A campanha de vacina\u00e7\u00e3o nas escolas mobilizou 365 unidades de ensino em 45 munic\u00edpios da \u00e1rea atendida pela Superintend\u00eancia Regional de Sa\u00fade de Pouso Alegre. A a\u00e7\u00e3o, realizada entre os dias 4 a 8 de maio, busca [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":16601,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[19,1876,5,1829],"tags":[8826,213,861,913,8399,184,37,5894,39,6865,27,8053,1618,8825,8824],"class_list":["post-16598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-saude","category-ultimas","category-utilidade","tag-campanha-de-vacinacao","tag-covid-19","tag-educacao","tag-governo-de-minas-gerais","tag-influenza","tag-minas-gerais","tag-pouso-alegre","tag-saude-publica","tag-sul-de-minas","tag-superintendencia-regional-de-saude","tag-tv-uai","tag-tv-uai-26-anos-ainda-estamos-aqui-ainda-independentes","tag-tv-uai-pouso-alegre","tag-vacinacao-infantil","tag-vacinacao-nas-escolas"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre - TVUAI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre - TVUAI\" \/>\n<meta property=\"og:description\" content=\"Campanha mobiliza escolas da regi\u00e3o de Pouso Alegre para ampliar cobertura vacinal de estudantes e profissionais da educa\u00e7\u00e3o A campanha de vacina\u00e7\u00e3o nas escolas mobilizou 365 unidades de ensino em 45 munic\u00edpios da \u00e1rea atendida pela Superintend\u00eancia Regional de Sa\u00fade de Pouso Alegre. A a\u00e7\u00e3o, realizada entre os dias 4 a 8 de maio, busca [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/\" \/>\n<meta property=\"og:site_name\" content=\"TVUAI\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica%c3%a7%c3%a3o\/139062546157369\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T11:50:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T21:49:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tvuai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tvuai\" \/>\n<meta name=\"twitter:site\" content=\"@tvuai\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"tvuai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/\"},\"author\":{\"name\":\"tvuai\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe\"},\"headline\":\"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre\",\"datePublished\":\"2026-05-07T11:50:45+00:00\",\"dateModified\":\"2026-05-07T21:49:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/\"},\"wordCount\":379,\"publisher\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1\",\"keywords\":[\"campanha de vacina\u00e7\u00e3o\",\"covid-19\",\"Educa\u00e7\u00e3o\",\"governo de Minas Gerais\",\"influenza\",\"Minas Gerais\",\"Pouso Alegre\",\"sa\u00fade p\u00fablica\",\"Sul de Minas\",\"Superintend\u00eancia Regional de Sa\u00fade\",\"TV Uai\",\"TV UAI 26 anos ainda estamos aqui ainda independentes\",\"TV UAI Pouso Alegre\",\"vacina\u00e7\u00e3o infantil\",\"vacina\u00e7\u00e3o nas escolas\"],\"articleSection\":[\"Not\u00edcias\",\"Sa\u00fade\",\"\u00daltimas Not\u00edcias\",\"Utilidade Publica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/\",\"name\":\"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre - TVUAI\",\"isPartOf\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1\",\"datePublished\":\"2026-05-07T11:50:45+00:00\",\"dateModified\":\"2026-05-07T21:49:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.tvuai.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#website\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/\",\"name\":\"TVUAI\",\"description\":\"Tudo sobre o Sul de Minas\",\"publisher\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tvuai.com.br\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\",\"name\":\"TVUAI\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1\",\"width\":207,\"height\":100,\"caption\":\"TVUAI\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica\u00e7\u00e3o\/139062546157369\",\"https:\/\/x.com\/tvuai\",\"https:\/\/www.instagram.com\/tvuai_network\/\",\"https:\/\/www.youtube.com\/channel\/UCB7ZPB3wRv-OpoZ_09jmnkQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe\",\"name\":\"tvuai\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/author\/tvuai\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre - TVUAI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/","og_locale":"pt_BR","og_type":"article","og_title":"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre - TVUAI","og_description":"Campanha mobiliza escolas da regi\u00e3o de Pouso Alegre para ampliar cobertura vacinal de estudantes e profissionais da educa\u00e7\u00e3o A campanha de vacina\u00e7\u00e3o nas escolas mobilizou 365 unidades de ensino em 45 munic\u00edpios da \u00e1rea atendida pela Superintend\u00eancia Regional de Sa\u00fade de Pouso Alegre. A a\u00e7\u00e3o, realizada entre os dias 4 a 8 de maio, busca [&hellip;]","og_url":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/","og_site_name":"TVUAI","article_publisher":"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica%c3%a7%c3%a3o\/139062546157369","article_published_time":"2026-05-07T11:50:45+00:00","article_modified_time":"2026-05-07T21:49:30+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg","type":"image\/jpeg"}],"author":"tvuai","twitter_card":"summary_large_image","twitter_creator":"@tvuai","twitter_site":"@tvuai","twitter_misc":{"Escrito por":"tvuai","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#article","isPartOf":{"@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/"},"author":{"name":"tvuai","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe"},"headline":"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre","datePublished":"2026-05-07T11:50:45+00:00","dateModified":"2026-05-07T21:49:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/"},"wordCount":379,"publisher":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#organization"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1","keywords":["campanha de vacina\u00e7\u00e3o","covid-19","Educa\u00e7\u00e3o","governo de Minas Gerais","influenza","Minas Gerais","Pouso Alegre","sa\u00fade p\u00fablica","Sul de Minas","Superintend\u00eancia Regional de Sa\u00fade","TV Uai","TV UAI 26 anos ainda estamos aqui ainda independentes","TV UAI Pouso Alegre","vacina\u00e7\u00e3o infantil","vacina\u00e7\u00e3o nas escolas"],"articleSection":["Not\u00edcias","Sa\u00fade","\u00daltimas Not\u00edcias","Utilidade Publica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/","url":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/","name":"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre - TVUAI","isPartOf":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#primaryimage"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1","datePublished":"2026-05-07T11:50:45+00:00","dateModified":"2026-05-07T21:49:30+00:00","breadcrumb":{"@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#primaryimage","url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.tvuai.com.br\/portal\/vacinacao-chega-a-365-escolas-em-45-cidades-da-regiao-atraves-da-regional-de-saude-de-pouso-alegre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.tvuai.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Vacina\u00e7\u00e3o chega a 365 escolas em 45 cidades da regi\u00e3o atrav\u00e9s da Regional de Sa\u00fade de Pouso Alegre"}]},{"@type":"WebSite","@id":"https:\/\/www.tvuai.com.br\/portal\/#website","url":"https:\/\/www.tvuai.com.br\/portal\/","name":"TVUAI","description":"Tudo sobre o Sul de Minas","publisher":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tvuai.com.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.tvuai.com.br\/portal\/#organization","name":"TVUAI","url":"https:\/\/www.tvuai.com.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1","width":207,"height":100,"caption":"TVUAI"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica\u00e7\u00e3o\/139062546157369","https:\/\/x.com\/tvuai","https:\/\/www.instagram.com\/tvuai_network\/","https:\/\/www.youtube.com\/channel\/UCB7ZPB3wRv-OpoZ_09jmnkQ"]},{"@type":"Person","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe","name":"tvuai","url":"https:\/\/www.tvuai.com.br\/portal\/author\/tvuai\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?resize=150%2C150&ssl=1",150,150,true],"cvmm-medium":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-medium-plus":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-portrait":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-medium-square":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-large":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-small":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?resize=130%2C95&ssl=1",130,95,true],"full":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/05\/vacina0.jpg?fit=200%2C200&ssl=1",200,200,false]},"categories_names":{"19":{"name":"Not\u00edcias","link":"https:\/\/www.tvuai.com.br\/portal\/category\/noticias\/"},"1876":{"name":"Sa\u00fade","link":"https:\/\/www.tvuai.com.br\/portal\/category\/saude\/"},"5":{"name":"\u00daltimas Not\u00edcias","link":"https:\/\/www.tvuai.com.br\/portal\/category\/noticias\/ultimas\/"},"1829":{"name":"Utilidade Publica","link":"https:\/\/www.tvuai.com.br\/portal\/category\/utilidade\/"}},"tags_names":{"8826":{"name":"campanha de vacina\u00e7\u00e3o","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/campanha-de-vacinacao\/"},"213":{"name":"covid-19","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/covid-19\/"},"861":{"name":"Educa\u00e7\u00e3o","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/educacao\/"},"913":{"name":"governo de Minas Gerais","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/governo-de-minas-gerais\/"},"8399":{"name":"influenza","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/influenza\/"},"184":{"name":"Minas Gerais","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/minas-gerais\/"},"37":{"name":"Pouso Alegre","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/pouso-alegre\/"},"5894":{"name":"sa\u00fade p\u00fablica","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/saude-publica\/"},"39":{"name":"Sul de Minas","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/sul-de-minas\/"},"6865":{"name":"Superintend\u00eancia Regional de Sa\u00fade","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/superintendencia-regional-de-saude\/"},"27":{"name":"TV Uai","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tv-uai\/"},"8053":{"name":"TV UAI 26 anos ainda estamos aqui ainda independentes","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tv-uai-26-anos-ainda-estamos-aqui-ainda-independentes\/"},"1618":{"name":"TV UAI Pouso Alegre","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tv-uai-pouso-alegre\/"},"8825":{"name":"vacina\u00e7\u00e3o infantil","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/vacinacao-infantil\/"},"8824":{"name":"vacina\u00e7\u00e3o nas escolas","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/vacinacao-nas-escolas\/"}},"comments_number":"0","jetpack_shortlink":"https:\/\/wp.me\/p9woix-4jI","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/16598"}],"collection":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/comments?post=16598"}],"version-history":[{"count":2,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/16598\/revisions"}],"predecessor-version":[{"id":16602,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/16598\/revisions\/16602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/media\/16601"}],"wp:attachment":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/media?parent=16598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/categories?post=16598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/tags?post=16598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}