{"id":16038,"date":"2026-03-25T17:06:12","date_gmt":"2026-03-25T20:06:12","guid":{"rendered":"https:\/\/www.tvuai.com.br\/portal\/?p=16038"},"modified":"2026-03-26T21:21:01","modified_gmt":"2026-03-27T00:21:01","slug":"apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva","status":"publish","type":"post","link":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/","title":{"rendered":"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva"},"content":{"rendered":"<div class=\"5a1038e0903b96d426fcfcc338703013\" data-index=\"1\" style=\"float: right; margin:10px 0 10px 10px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-9945944833605257\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-9945944833605257\"\r\n     data-ad-slot=\"2343923581\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p data-start=\"99\" data-end=\"420\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"16042\" data-permalink=\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/bombeirosedefesacivil1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil1.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1774475518&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bombeirosedefesacivil1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil1.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil1.jpg?fit=640%2C480&amp;ssl=1\" tabindex=\"0\" role=\"button\" class=\"aligncenter size-full wp-image-16042\" src=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil1.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil1.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil1.jpg?resize=136%2C102&amp;ssl=1 136w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>Represas e barragens localizadas na zona rural de Pouso Alegre passaram por uma opera\u00e7\u00e3o de vistoria preventiva nesta ter\u00e7a-feira, 24. A a\u00e7\u00e3o foi realizada para avaliar as condi\u00e7\u00f5es estruturais das represas ap\u00f3s o per\u00edodo de chuvas e identificar poss\u00edveis riscos relacionados ao funcionamento dessas estruturas.<\/p>\n<p data-start=\"422\" data-end=\"655\">A iniciativa contou com equipes da Defesa Civil Municipal, \u00f3rg\u00e3o vinculado \u00e0 Secretaria Municipal de Seguran\u00e7a P\u00fablica, com apoio da Secretaria Municipal de Agricultura, Pecu\u00e1ria e Abastecimento, em parceria com o Corpo de Bombeiros.<\/p>\n<p data-start=\"657\" data-end=\"868\">Durante a opera\u00e7\u00e3o, os profissionais analisaram a estrutura das barragens e verificaram poss\u00edveis situa\u00e7\u00f5es de risco, al\u00e9m de observar as condi\u00e7\u00f5es de opera\u00e7\u00e3o das represas existentes na \u00e1rea rural do munic\u00edpio.<\/p>\n<p data-start=\"870\" data-end=\"1042\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"16043\" data-permalink=\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/bombeirosedefesacivil2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil2.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1774475562&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bombeirosedefesacivil2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil2.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil2.jpg?fit=640%2C480&amp;ssl=1\" tabindex=\"0\" role=\"button\" class=\"alignleft size-medium wp-image-16043\" src=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil2.jpg?resize=300%2C225&#038;ssl=1\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil2.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil2.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil2.jpg?resize=136%2C102&amp;ssl=1 136w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil2.jpg?w=800&amp;ssl=1 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Segundo a engenheira da Defesa Civil e gerente do Departamento T\u00e9cnico, Amanda Corsini, a a\u00e7\u00e3o tem car\u00e1ter preventivo e busca garantir maior seguran\u00e7a para a popula\u00e7\u00e3o.<\/p>\n<p data-start=\"1044\" data-end=\"1233\">Ela explicou que as equipes est\u00e3o avaliando as condi\u00e7\u00f5es das represas e poss\u00edveis riscos, especialmente ap\u00f3s o per\u00edodo de chuvas, quando o volume de \u00e1gua costuma aumentar nessas estruturas.<\/p>\n<p data-start=\"1235\" data-end=\"1480\">O 1\u00ba tenente do Corpo de Bombeiros, Anderson Ferraz de Aquino, destacou que a vistoria tamb\u00e9m analisa fatores relacionados \u00e0 opera\u00e7\u00e3o das barragens e a exist\u00eancia de moradores ou bens em \u00e1reas que poderiam ser afetadas em caso de incidentes.<\/p>\n<p data-start=\"1482\" data-end=\"1704\"><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"16044\" data-permalink=\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/bombeirosedefesacivil3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil3.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1774475604&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"bombeirosedefesacivil3\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil3.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil3.jpg?fit=640%2C480&amp;ssl=1\" tabindex=\"0\" role=\"button\" class=\"alignright size-medium wp-image-16044\" src=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil3.jpg?resize=300%2C225&#038;ssl=1\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil3.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil3.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil3.jpg?resize=136%2C102&amp;ssl=1 136w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil3.jpg?w=800&amp;ssl=1 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>De acordo com o militar, as informa\u00e7\u00f5es coletadas durante a opera\u00e7\u00e3o s\u00e3o importantes para subsidiar a elabora\u00e7\u00e3o de planos de a\u00e7\u00e3o emergencial, caso ocorra algum evento adverso, como o rompimento de barragens no munic\u00edpio.<\/p>\n<p data-start=\"1706\" data-end=\"1958\">A Prefeitura informou que a\u00e7\u00f5es desse tipo fazem parte do monitoramento cont\u00ednuo das estruturas h\u00eddricas da cidade e s\u00e3o consideradas essenciais para refor\u00e7ar a seguran\u00e7a das comunidades rurais, principalmente em per\u00edodos de maior incid\u00eancia de chuvas.<\/p>\n<h6 style=\"text-align: right;\" data-start=\"1706\" data-end=\"1958\"><em><strong>Com informa\u00e7\u00f5es de Rafael Lemes e fotos Ascom\/PA<\/strong><\/em><\/h6>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva' data-link='https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Represas e barragens localizadas na zona rural de Pouso Alegre passaram por uma opera\u00e7\u00e3o de vistoria preventiva nesta ter\u00e7a-feira, 24. A a\u00e7\u00e3o foi realizada para avaliar as condi\u00e7\u00f5es estruturais das represas ap\u00f3s o per\u00edodo de chuvas e identificar poss\u00edveis riscos relacionados ao funcionamento dessas estruturas. A iniciativa contou com equipes da Defesa Civil Municipal, \u00f3rg\u00e3o [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":16041,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1969,5787,19,1876,5,1829],"tags":[8256,7743,4106,490,184,37,8536,769,6325,8533,4328,39,27,8053,1618,8535,8534],"class_list":["post-16038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricultura","category-meio-ambiente","category-noticias","category-saude","category-ultimas","category-utilidade","tag-barragens","tag-chuvas","tag-corpo-de-bombeiros","tag-defesa-civil","tag-minas-gerais","tag-pouso-alegre","tag-pouso-alegre-mg","tag-prefeitura-de-pouso-alegre","tag-prevencao","tag-represas","tag-seguranca-publica","tag-sul-de-minas","tag-tv-uai","tag-tv-uai-26-anos-ainda-estamos-aqui-ainda-independentes","tag-tv-uai-pouso-alegre","tag-vistoria","tag-zona-rural"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva - TVUAI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva - TVUAI\" \/>\n<meta property=\"og:description\" content=\"Represas e barragens localizadas na zona rural de Pouso Alegre passaram por uma opera\u00e7\u00e3o de vistoria preventiva nesta ter\u00e7a-feira, 24. A a\u00e7\u00e3o foi realizada para avaliar as condi\u00e7\u00f5es estruturais das represas ap\u00f3s o per\u00edodo de chuvas e identificar poss\u00edveis riscos relacionados ao funcionamento dessas estruturas. A iniciativa contou com equipes da Defesa Civil Municipal, \u00f3rg\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/\" \/>\n<meta property=\"og:site_name\" content=\"TVUAI\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica%c3%a7%c3%a3o\/139062546157369\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T20:06:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T00:21:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tvuai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tvuai\" \/>\n<meta name=\"twitter:site\" content=\"@tvuai\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"tvuai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/\"},\"author\":{\"name\":\"tvuai\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe\"},\"headline\":\"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva\",\"datePublished\":\"2026-03-25T20:06:12+00:00\",\"dateModified\":\"2026-03-27T00:21:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/\"},\"wordCount\":340,\"publisher\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1\",\"keywords\":[\"barragens\",\"chuvas\",\"Corpo de Bombeiros\",\"defesa civil\",\"Minas Gerais\",\"Pouso Alegre\",\"pouso alegre mg\",\"Prefeitura de Pouso Alegre\",\"Preven\u00e7\u00e3o\",\"represas\",\"Seguran\u00e7a P\u00fablica\",\"Sul de Minas\",\"TV Uai\",\"TV UAI 26 anos ainda estamos aqui ainda independentes\",\"TV UAI Pouso Alegre\",\"vistoria\",\"zona rural\"],\"articleSection\":[\"Agricultura\",\"Meio Ambiente\",\"Not\u00edcias\",\"Sa\u00fade\",\"\u00daltimas Not\u00edcias\",\"Utilidade Publica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/\",\"name\":\"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva - TVUAI\",\"isPartOf\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1\",\"datePublished\":\"2026-03-25T20:06:12+00:00\",\"dateModified\":\"2026-03-27T00:21:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.tvuai.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#website\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/\",\"name\":\"TVUAI\",\"description\":\"Tudo sobre o Sul de Minas\",\"publisher\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tvuai.com.br\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\",\"name\":\"TVUAI\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1\",\"width\":207,\"height\":100,\"caption\":\"TVUAI\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica\u00e7\u00e3o\/139062546157369\",\"https:\/\/x.com\/tvuai\",\"https:\/\/www.instagram.com\/tvuai_network\/\",\"https:\/\/www.youtube.com\/channel\/UCB7ZPB3wRv-OpoZ_09jmnkQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe\",\"name\":\"tvuai\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/author\/tvuai\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva - TVUAI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/","og_locale":"pt_BR","og_type":"article","og_title":"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva - TVUAI","og_description":"Represas e barragens localizadas na zona rural de Pouso Alegre passaram por uma opera\u00e7\u00e3o de vistoria preventiva nesta ter\u00e7a-feira, 24. A a\u00e7\u00e3o foi realizada para avaliar as condi\u00e7\u00f5es estruturais das represas ap\u00f3s o per\u00edodo de chuvas e identificar poss\u00edveis riscos relacionados ao funcionamento dessas estruturas. A iniciativa contou com equipes da Defesa Civil Municipal, \u00f3rg\u00e3o [&hellip;]","og_url":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/","og_site_name":"TVUAI","article_publisher":"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica%c3%a7%c3%a3o\/139062546157369","article_published_time":"2026-03-25T20:06:12+00:00","article_modified_time":"2026-03-27T00:21:01+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg","type":"image\/jpeg"}],"author":"tvuai","twitter_card":"summary_large_image","twitter_creator":"@tvuai","twitter_site":"@tvuai","twitter_misc":{"Escrito por":"tvuai","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#article","isPartOf":{"@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/"},"author":{"name":"tvuai","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe"},"headline":"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva","datePublished":"2026-03-25T20:06:12+00:00","dateModified":"2026-03-27T00:21:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/"},"wordCount":340,"publisher":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#organization"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1","keywords":["barragens","chuvas","Corpo de Bombeiros","defesa civil","Minas Gerais","Pouso Alegre","pouso alegre mg","Prefeitura de Pouso Alegre","Preven\u00e7\u00e3o","represas","Seguran\u00e7a P\u00fablica","Sul de Minas","TV Uai","TV UAI 26 anos ainda estamos aqui ainda independentes","TV UAI Pouso Alegre","vistoria","zona rural"],"articleSection":["Agricultura","Meio Ambiente","Not\u00edcias","Sa\u00fade","\u00daltimas Not\u00edcias","Utilidade Publica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/","url":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/","name":"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva - TVUAI","isPartOf":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#primaryimage"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1","datePublished":"2026-03-25T20:06:12+00:00","dateModified":"2026-03-27T00:21:01+00:00","breadcrumb":{"@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#primaryimage","url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.tvuai.com.br\/portal\/apos-chuvas-represas-da-zona-rural-de-pouso-alegre-passam-por-vistoria-preventiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.tvuai.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Ap\u00f3s chuvas, represas da zona rural de Pouso Alegre passam por vistoria preventiva"}]},{"@type":"WebSite","@id":"https:\/\/www.tvuai.com.br\/portal\/#website","url":"https:\/\/www.tvuai.com.br\/portal\/","name":"TVUAI","description":"Tudo sobre o Sul de Minas","publisher":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tvuai.com.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.tvuai.com.br\/portal\/#organization","name":"TVUAI","url":"https:\/\/www.tvuai.com.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1","width":207,"height":100,"caption":"TVUAI"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica\u00e7\u00e3o\/139062546157369","https:\/\/x.com\/tvuai","https:\/\/www.instagram.com\/tvuai_network\/","https:\/\/www.youtube.com\/channel\/UCB7ZPB3wRv-OpoZ_09jmnkQ"]},{"@type":"Person","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe","name":"tvuai","url":"https:\/\/www.tvuai.com.br\/portal\/author\/tvuai\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?resize=150%2C150&ssl=1",150,150,true],"cvmm-medium":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-medium-plus":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-portrait":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-medium-square":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-large":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-small":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?resize=130%2C95&ssl=1",130,95,true],"full":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2026\/03\/bombeirosedefesacivil0.jpg?fit=200%2C200&ssl=1",200,200,false]},"categories_names":{"1969":{"name":"Agricultura","link":"https:\/\/www.tvuai.com.br\/portal\/category\/agricultura\/"},"5787":{"name":"Meio Ambiente","link":"https:\/\/www.tvuai.com.br\/portal\/category\/meio-ambiente\/"},"19":{"name":"Not\u00edcias","link":"https:\/\/www.tvuai.com.br\/portal\/category\/noticias\/"},"1876":{"name":"Sa\u00fade","link":"https:\/\/www.tvuai.com.br\/portal\/category\/saude\/"},"5":{"name":"\u00daltimas Not\u00edcias","link":"https:\/\/www.tvuai.com.br\/portal\/category\/noticias\/ultimas\/"},"1829":{"name":"Utilidade Publica","link":"https:\/\/www.tvuai.com.br\/portal\/category\/utilidade\/"}},"tags_names":{"8256":{"name":"barragens","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/barragens\/"},"7743":{"name":"chuvas","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/chuvas\/"},"4106":{"name":"Corpo de Bombeiros","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/corpo-de-bombeiros\/"},"490":{"name":"defesa civil","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/defesa-civil\/"},"184":{"name":"Minas Gerais","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/minas-gerais\/"},"37":{"name":"Pouso Alegre","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/pouso-alegre\/"},"8536":{"name":"pouso alegre mg","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/pouso-alegre-mg\/"},"769":{"name":"Prefeitura de Pouso Alegre","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/prefeitura-de-pouso-alegre\/"},"6325":{"name":"Preven\u00e7\u00e3o","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/prevencao\/"},"8533":{"name":"represas","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/represas\/"},"4328":{"name":"Seguran\u00e7a P\u00fablica","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/seguranca-publica\/"},"39":{"name":"Sul de Minas","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/sul-de-minas\/"},"27":{"name":"TV Uai","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tv-uai\/"},"8053":{"name":"TV UAI 26 anos ainda estamos aqui ainda independentes","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tv-uai-26-anos-ainda-estamos-aqui-ainda-independentes\/"},"1618":{"name":"TV UAI Pouso Alegre","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tv-uai-pouso-alegre\/"},"8535":{"name":"vistoria","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/vistoria\/"},"8534":{"name":"zona rural","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/zona-rural\/"}},"comments_number":"0","jetpack_shortlink":"https:\/\/wp.me\/p9woix-4aG","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/16038"}],"collection":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/comments?post=16038"}],"version-history":[{"count":3,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/16038\/revisions"}],"predecessor-version":[{"id":16045,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/16038\/revisions\/16045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/media\/16041"}],"wp:attachment":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/media?parent=16038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/categories?post=16038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/tags?post=16038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}