{"id":12044,"date":"2025-06-11T17:25:00","date_gmt":"2025-06-11T20:25:00","guid":{"rendered":"https:\/\/www.tvuai.com.br\/portal\/?p=12044"},"modified":"2025-06-13T17:52:52","modified_gmt":"2025-06-13T20:52:52","slug":"descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi","status":"publish","type":"post","link":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/","title":{"rendered":"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi"},"content":{"rendered":"<div class=\"5a1038e0903b96d426fcfcc338703013\" data-index=\"1\" style=\"float: right; margin:10px 0 10px 10px;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-9945944833605257\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-9945944833605257\"\r\n     data-ad-slot=\"2343923581\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<h5 style=\"text-align: center;\" data-start=\"274\" data-end=\"486\"><strong><em data-start=\"274\" data-end=\"486\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"12047\" data-permalink=\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/arqueoloporta1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta1.jpg?fit=1000%2C665&amp;ssl=1\" data-orig-size=\"1000,665\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"arqueoloporta1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta1.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta1.jpg?fit=640%2C426&amp;ssl=1\" tabindex=\"0\" role=\"button\" class=\"alignright size-full wp-image-12047\" src=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta1.jpg?resize=640%2C426&#038;ssl=1\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta1.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta1.jpg?resize=768%2C511&amp;ssl=1 768w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>Pesquisadores encontram antiga porta de cidade fortificada em escava\u00e7\u00f5es na regi\u00e3o pr\u00f3xima ao mar da Galileia Artefato remonta \u00e0 \u00e9poca do rei Davi e levanta novas hip\u00f3teses sobre o dom\u00ednio israelita na regi\u00e3o<\/em><\/strong><\/h5>\n<p data-start=\"488\" data-end=\"829\">Uma equipe de arque\u00f3logos da Universidade de Nebraska, em parceria com pesquisadores israelenses, revelou uma descoberta impressionante nas Colinas de Gol\u00e3, territ\u00f3rio localizado a nordeste do mar da Galileia: uma antiga porta de cidade que, segundo os especialistas, remonta \u00e0 \u00e9poca do rei Davi e pode estar relacionada a relatos b\u00edblicos.<\/p>\n<p data-start=\"831\" data-end=\"1166\">O achado foi encontrado na antiga cidade de Betsaida, no Parque Jord\u00e3o das Colinas de Gol\u00e3, como parte de um projeto de escava\u00e7\u00f5es iniciado h\u00e1 mais de tr\u00eas d\u00e9cadas. A estrutura, identificada como um port\u00e3o fortificado, data dos s\u00e9culos X a XI a.C., per\u00edodo que coincide com o reinado do rei Davi e \u00e9 conhecido como a era do Primeiro Templo.<\/p>\n<p data-start=\"1168\" data-end=\"1584\">Segundo os arque\u00f3logos, a porta integrava as muralhas de prote\u00e7\u00e3o da cidade, um tra\u00e7o comum nos pequenos assentamentos daquela \u00e9poca, que se precaviam contra invasores. Por estar muito bem preservada, a remo\u00e7\u00e3o da estrutura exigiu um cuidadoso processo para n\u00e3o comprometer sua integridade. At\u00e9 o momento, ela \u00e9 considerada a mais antiga entre as portas j\u00e1 localizadas em cidades associadas \u00e0 hist\u00f3ria do povo judeu.<\/p>\n<p data-start=\"1586\" data-end=\"2004\">Em entrevista ao <em data-start=\"1603\" data-end=\"1623\">The Jerusalem Post<\/em>, a professora Rami Arav, da Universidade de Nebraska, destacou a conex\u00e3o entre a descoberta e passagens b\u00edblicas. Ela explicou que, durante o per\u00edodo do Segundo Templo, a cidade era conhecida como Betsaida, mas nos tempos do Primeiro Templo era chamada de Zer \u2014 conforme registrado em Josu\u00e9 19:35, onde s\u00e3o citadas cidades fortificadas como Zidim, Zer, Hamate, Recate e Quinerete.<\/p>\n<p data-start=\"2006\" data-end=\"2470\">A descoberta tamb\u00e9m levantou novos debates entre os estudiosos. As evid\u00eancias encontradas nas ru\u00ednas ao redor da porta, incluindo uma escultura do deus lunar em forma de touro \u2014 uma figura t\u00edpica da cultura arameia do s\u00e9culo XI a.C. \u2014 sugerem que a cidade pode ter pertencido a um dom\u00ednio arameu, e n\u00e3o judeu. Isso fortalece a hip\u00f3tese de que Davi teria sido um l\u00edder tribal regional, ao inv\u00e9s de um monarca de um reino unificado como tradicionalmente se acredita.<\/p>\n<p data-start=\"2472\" data-end=\"2706\">Outro destaque da escava\u00e7\u00e3o foi a localiza\u00e7\u00e3o de joias e moedas de ouro. Uma das moedas encontradas, datada de 35 a.C., homenageia Cle\u00f3patra e Marco Ant\u00f4nio \u2014 e \u00e9 considerada uma raridade, com apenas 12 exemplares conhecidos no mundo.<\/p>\n<p data-start=\"2708\" data-end=\"3023\">O local de Betsaida tamb\u00e9m tem longa tradi\u00e7\u00e3o como ponto de peregrina\u00e7\u00e3o crist\u00e3, devido \u00e0 sua import\u00e2ncia hist\u00f3rica e simb\u00f3lica. No mesmo s\u00edtio, os arque\u00f3logos localizaram vest\u00edgios de um templo romano constru\u00eddo no s\u00e9culo I pelo imperador Filipe, filho de Herodes, em homenagem a J\u00falia, filha do imperador Augusto.<\/p>\n<p data-start=\"3025\" data-end=\"3420\">A descoberta da porta de Betsaida se soma a outro achado recente de grande relev\u00e2ncia arqueol\u00f3gica: um fosso monumental de defesa foi identificado nas proximidades da chamada Cidade de Davi, em Jerusal\u00e9m. Datado da Idade do Ferro, o fosso teria cerca de 3 mil anos e \u00e9 citado na B\u00edblia, em passagens do Livro dos Reis e do Livro de Samuel, como parte das obras defensivas realizadas por Salom\u00e3o.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi' data-link='https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Pesquisadores encontram antiga porta de cidade fortificada em escava\u00e7\u00f5es na regi\u00e3o pr\u00f3xima ao mar da Galileia Artefato remonta \u00e0 \u00e9poca do rei Davi e levanta novas hip\u00f3teses sobre o dom\u00ednio israelita na regi\u00e3o Uma equipe de arque\u00f3logos da Universidade de Nebraska, em parceria com pesquisadores israelenses, revelou uma descoberta impressionante nas Colinas de Gol\u00e3, territ\u00f3rio [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":12046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1642,19,1830,5],"tags":[5493,5496,5494,184,5497,5498,37,5495,39,27,1618,4796],"class_list":["post-12044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","category-noticias","category-religiao","category-ultimas","tag-arqueologos-da-universidade-de-nebraska","tag-betsaida","tag-colinas-de-gola","tag-minas-gerais","tag-parque-jordao-das-colinas-de-gola","tag-portao-fortificado-dos-seculos-x-a-xi-a-c","tag-pouso-alegre","tag-rei-davi","tag-sul-de-minas","tag-tv-uai","tag-tv-uai-pouso-alegre","tag-tvuai25"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi - TVUAI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi - TVUAI\" \/>\n<meta property=\"og:description\" content=\"Pesquisadores encontram antiga porta de cidade fortificada em escava\u00e7\u00f5es na regi\u00e3o pr\u00f3xima ao mar da Galileia Artefato remonta \u00e0 \u00e9poca do rei Davi e levanta novas hip\u00f3teses sobre o dom\u00ednio israelita na regi\u00e3o Uma equipe de arque\u00f3logos da Universidade de Nebraska, em parceria com pesquisadores israelenses, revelou uma descoberta impressionante nas Colinas de Gol\u00e3, territ\u00f3rio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/\" \/>\n<meta property=\"og:site_name\" content=\"TVUAI\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica%c3%a7%c3%a3o\/139062546157369\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-11T20:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-13T20:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tvuai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tvuai\" \/>\n<meta name=\"twitter:site\" content=\"@tvuai\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"tvuai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/\"},\"author\":{\"name\":\"tvuai\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe\"},\"headline\":\"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi\",\"datePublished\":\"2025-06-11T20:25:00+00:00\",\"dateModified\":\"2025-06-13T20:52:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/\"},\"wordCount\":573,\"publisher\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1\",\"keywords\":[\"arque\u00f3logos da Universidade de Nebraska\",\"Betsaida\",\"Colinas de Gol\u00e3\",\"Minas Gerais\",\"Parque Jord\u00e3o das Colinas de Gol\u00e3\",\"port\u00e3o fortificado dos s\u00e9culos X a XI a.C.\",\"Pouso Alegre\",\"rei Davi\",\"Sul de Minas\",\"TV Uai\",\"TV UAI Pouso Alegre\",\"TVUAI25\"],\"articleSection\":[\"Ci\u00eancia e Tecnologia\",\"Not\u00edcias\",\"Religi\u00e3o\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/\",\"name\":\"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi - TVUAI\",\"isPartOf\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1\",\"datePublished\":\"2025-06-11T20:25:00+00:00\",\"dateModified\":\"2025-06-13T20:52:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.tvuai.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#website\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/\",\"name\":\"TVUAI\",\"description\":\"Tudo sobre o Sul de Minas\",\"publisher\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tvuai.com.br\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#organization\",\"name\":\"TVUAI\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1\",\"width\":207,\"height\":100,\"caption\":\"TVUAI\"},\"image\":{\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica\u00e7\u00e3o\/139062546157369\",\"https:\/\/x.com\/tvuai\",\"https:\/\/www.instagram.com\/tvuai_network\/\",\"https:\/\/www.youtube.com\/channel\/UCB7ZPB3wRv-OpoZ_09jmnkQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe\",\"name\":\"tvuai\",\"url\":\"https:\/\/www.tvuai.com.br\/portal\/author\/tvuai\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi - TVUAI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/","og_locale":"pt_BR","og_type":"article","og_title":"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi - TVUAI","og_description":"Pesquisadores encontram antiga porta de cidade fortificada em escava\u00e7\u00f5es na regi\u00e3o pr\u00f3xima ao mar da Galileia Artefato remonta \u00e0 \u00e9poca do rei Davi e levanta novas hip\u00f3teses sobre o dom\u00ednio israelita na regi\u00e3o Uma equipe de arque\u00f3logos da Universidade de Nebraska, em parceria com pesquisadores israelenses, revelou uma descoberta impressionante nas Colinas de Gol\u00e3, territ\u00f3rio [&hellip;]","og_url":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/","og_site_name":"TVUAI","article_publisher":"http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica%c3%a7%c3%a3o\/139062546157369","article_published_time":"2025-06-11T20:25:00+00:00","article_modified_time":"2025-06-13T20:52:52+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg","type":"image\/jpeg"}],"author":"tvuai","twitter_card":"summary_large_image","twitter_creator":"@tvuai","twitter_site":"@tvuai","twitter_misc":{"Escrito por":"tvuai","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#article","isPartOf":{"@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/"},"author":{"name":"tvuai","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe"},"headline":"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi","datePublished":"2025-06-11T20:25:00+00:00","dateModified":"2025-06-13T20:52:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/"},"wordCount":573,"publisher":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#organization"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1","keywords":["arque\u00f3logos da Universidade de Nebraska","Betsaida","Colinas de Gol\u00e3","Minas Gerais","Parque Jord\u00e3o das Colinas de Gol\u00e3","port\u00e3o fortificado dos s\u00e9culos X a XI a.C.","Pouso Alegre","rei Davi","Sul de Minas","TV Uai","TV UAI Pouso Alegre","TVUAI25"],"articleSection":["Ci\u00eancia e Tecnologia","Not\u00edcias","Religi\u00e3o","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/","url":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/","name":"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi - TVUAI","isPartOf":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#primaryimage"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1","datePublished":"2025-06-11T20:25:00+00:00","dateModified":"2025-06-13T20:52:52+00:00","breadcrumb":{"@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#primaryimage","url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.tvuai.com.br\/portal\/descoberta-arqueologica-nas-colinas-de-gola-pode-confirmar-relatos-biblicos-sobre-o-rei-davi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.tvuai.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Descoberta arqueol\u00f3gica nas Colinas de Gol\u00e3 pode confirmar relatos b\u00edblicos sobre o Rei Davi"}]},{"@type":"WebSite","@id":"https:\/\/www.tvuai.com.br\/portal\/#website","url":"https:\/\/www.tvuai.com.br\/portal\/","name":"TVUAI","description":"Tudo sobre o Sul de Minas","publisher":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tvuai.com.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.tvuai.com.br\/portal\/#organization","name":"TVUAI","url":"https:\/\/www.tvuai.com.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2017\/12\/logo_tvuai_100H.png?fit=207%2C100&ssl=1","width":207,"height":100,"caption":"TVUAI"},"image":{"@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/pages\/TV-Uai-Comunica\u00e7\u00e3o\/139062546157369","https:\/\/x.com\/tvuai","https:\/\/www.instagram.com\/tvuai_network\/","https:\/\/www.youtube.com\/channel\/UCB7ZPB3wRv-OpoZ_09jmnkQ"]},{"@type":"Person","@id":"https:\/\/www.tvuai.com.br\/portal\/#\/schema\/person\/245e50e9127451fd0b7fd76f519ebbfe","name":"tvuai","url":"https:\/\/www.tvuai.com.br\/portal\/author\/tvuai\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?resize=150%2C150&ssl=1",150,150,true],"cvmm-medium":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-medium-plus":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-portrait":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-medium-square":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-large":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?resize=200%2C200&ssl=1",200,200,true],"cvmm-small":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?resize=130%2C95&ssl=1",130,95,true],"full":["https:\/\/i0.wp.com\/www.tvuai.com.br\/portal\/wp-content\/uploads\/2025\/06\/arqueoloporta0.jpg?fit=200%2C200&ssl=1",200,200,false]},"categories_names":{"1642":{"name":"Ci\u00eancia e Tecnologia","link":"https:\/\/www.tvuai.com.br\/portal\/category\/tecnologia\/"},"19":{"name":"Not\u00edcias","link":"https:\/\/www.tvuai.com.br\/portal\/category\/noticias\/"},"1830":{"name":"Religi\u00e3o","link":"https:\/\/www.tvuai.com.br\/portal\/category\/religiao\/"},"5":{"name":"\u00daltimas Not\u00edcias","link":"https:\/\/www.tvuai.com.br\/portal\/category\/noticias\/ultimas\/"}},"tags_names":{"5493":{"name":"arque\u00f3logos da Universidade de Nebraska","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/arqueologos-da-universidade-de-nebraska\/"},"5496":{"name":"Betsaida","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/betsaida\/"},"5494":{"name":"Colinas de Gol\u00e3","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/colinas-de-gola\/"},"184":{"name":"Minas Gerais","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/minas-gerais\/"},"5497":{"name":"Parque Jord\u00e3o das Colinas de Gol\u00e3","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/parque-jordao-das-colinas-de-gola\/"},"5498":{"name":"port\u00e3o fortificado dos s\u00e9culos X a XI a.C.","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/portao-fortificado-dos-seculos-x-a-xi-a-c\/"},"37":{"name":"Pouso Alegre","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/pouso-alegre\/"},"5495":{"name":"rei Davi","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/rei-davi\/"},"39":{"name":"Sul de Minas","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/sul-de-minas\/"},"27":{"name":"TV Uai","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tv-uai\/"},"1618":{"name":"TV UAI Pouso Alegre","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tv-uai-pouso-alegre\/"},"4796":{"name":"TVUAI25","link":"https:\/\/www.tvuai.com.br\/portal\/tag\/tvuai25\/"}},"comments_number":"0","jetpack_shortlink":"https:\/\/wp.me\/p9woix-38g","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/12044"}],"collection":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/comments?post=12044"}],"version-history":[{"count":2,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/12044\/revisions"}],"predecessor-version":[{"id":12048,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/posts\/12044\/revisions\/12048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/media\/12046"}],"wp:attachment":[{"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/media?parent=12044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/categories?post=12044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tvuai.com.br\/portal\/wp-json\/wp\/v2\/tags?post=12044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}